{"id":29770,"date":"2021-01-01T00:00:00","date_gmt":"2021-01-01T00:00:00","guid":{"rendered":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/"},"modified":"2024-02-02T14:04:32","modified_gmt":"2024-02-02T14:04:32","slug":"original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/","title":{"rendered":"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study"},"content":{"rendered":"<p>Kahan, Z; Gil-Gil, M; Ruiz-Borrego, M; Carrasco, E; Ciruelos, E; Munoz, M; Bermejo, B; Margeli, M; Anton, A; Casas, M; Csoszi, T; Murillo, L; Morales, S; Calvo, L; Lang, I; Alba, E; de la Haba-Rodriguez, J; Ramos, M; Lopez, IA; Gal-Yam, E; Garcia-Palomo, A; Alvarez, E; Gonzalez-Santiago, S; Rodriguez, CA; Servitja, S; Corsaro, M; Rodrigalvarez, G; Zielinski, C; Martin, M &#8211; 2021<\/p>","protected":false},"excerpt":{"rendered":"<p>Kahan, Z; Gil-Gil, M; Ruiz-Borrego, M; Carrasco, E; Ciruelos, E; Munoz, M; Bermejo, B; Margeli, M; Anton, A; Casas, M; Csoszi, T; Murillo, L; Morales, S; Calvo, L; Lang, I; Alba, E; de la Haba-Rodriguez, J; Ramos, M; Lopez, IA; Gal-Yam, E; Garcia-Palomo, A; Alvarez, E; Gonzalez-Santiago, S; Rodriguez, CA; Servitja, S; Corsaro, M; Rodrigalvarez, G; Zielinski, C; Martin, M &#8211; 2021<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1592],"tags":[],"class_list":["post-29770","post","type-post","status-publish","format-standard","hentry","category-publicaciones-b-01"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study - Ibima\" \/>\n<meta property=\"og:description\" content=\"Kahan, Z; Gil-Gil, M; Ruiz-Borrego, M; Carrasco, E; Ciruelos, E; Munoz, M; Bermejo, B; Margeli, M; Anton, A; Casas, M; Csoszi, T; Murillo, L; Morales, S; Calvo, L; Lang, I; Alba, E; de la Haba-Rodriguez, J; Ramos, M; Lopez, IA; Gal-Yam, E; Garcia-Palomo, A; Alvarez, E; Gonzalez-Santiago, S; Rodriguez, CA; Servitja, S; Corsaro, M; Rodrigalvarez, G; Zielinski, C; Martin, M - 2021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T14:04:32+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study\",\"datePublished\":\"2021-01-01T00:00:00+00:00\",\"dateModified\":\"2024-02-02T14:04:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/\"},\"wordCount\":89,\"commentCount\":0,\"articleSection\":[\"Publicaciones - B-01\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/\",\"name\":\"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2021-01-01T00:00:00+00:00\",\"dateModified\":\"2024-02-02T14:04:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/","og_locale":"en_GB","og_type":"article","og_title":"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study - Ibima","og_description":"Kahan, Z; Gil-Gil, M; Ruiz-Borrego, M; Carrasco, E; Ciruelos, E; Munoz, M; Bermejo, B; Margeli, M; Anton, A; Casas, M; Csoszi, T; Murillo, L; Morales, S; Calvo, L; Lang, I; Alba, E; de la Haba-Rodriguez, J; Ramos, M; Lopez, IA; Gal-Yam, E; Garcia-Palomo, A; Alvarez, E; Gonzalez-Santiago, S; Rodriguez, CA; Servitja, S; Corsaro, M; Rodrigalvarez, G; Zielinski, C; Martin, M - 2021","og_url":"https:\/\/ibima.eu\/en\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/","og_site_name":"Ibima","article_published_time":"2021-01-01T00:00:00+00:00","article_modified_time":"2024-02-02T14:04:32+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study","datePublished":"2021-01-01T00:00:00+00:00","dateModified":"2024-02-02T14:04:32+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/"},"wordCount":89,"commentCount":0,"articleSection":["Publicaciones - B-01"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/","url":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/","name":"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2021-01-01T00:00:00+00:00","dateModified":"2024-02-02T14:04:32+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/original-research-health-related-quality-of-life-with-palbociclib-plus-endocrine-therapy-versus-capecitabine-in-postmenopausal-patients-with-hormone-receptor-positive-metastatic-breast-cancer-patient\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Original Research Health-related quality of life with palbociclib plus endocrine therapy versus capecitabine in postmenopausal patients with hormone receptor-positive metastatic breast cancer: Patient-reported outcomes in the PEARL study"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/29770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=29770"}],"version-history":[{"count":0,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/29770\/revisions"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=29770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=29770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=29770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}