{"id":32298,"date":"2025-07-30T08:40:42","date_gmt":"2025-07-30T08:40:42","guid":{"rendered":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/"},"modified":"2025-07-30T08:40:42","modified_gmt":"2025-07-30T08:40:42","slug":"ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/","title":{"rendered":"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN)"},"content":{"rendered":"<p>INMACULADA AL\u00c9S D\u00cdAZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; ASTRAZENECA AB<\/p>","protected":false},"excerpt":{"rendered":"<p>INMACULADA AL\u00c9S D\u00cdAZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; ASTRAZENECA AB<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2683],"tags":[],"class_list":["post-32298","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-b-22"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN) - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN) - Ibima\" \/>\n<meta property=\"og:description\" content=\"INMACULADA AL\u00c9S D\u00cdAZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; ASTRAZENECA AB\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:40:42+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\\\/GEJC) (MATTERHORN)\",\"datePublished\":\"2025-07-30T08:40:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/\"},\"wordCount\":52,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - B-22\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/\",\"name\":\"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\\\/GEJC) (MATTERHORN) - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:40:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\\\/GEJC) (MATTERHORN)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN) - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/","og_locale":"en_GB","og_type":"article","og_title":"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN) - Ibima","og_description":"INMACULADA AL\u00c9S D\u00cdAZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; ASTRAZENECA AB","og_url":"https:\/\/ibima.eu\/en\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:40:42+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN)","datePublished":"2025-07-30T08:40:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/"},"wordCount":52,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - B-22"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/","url":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/","name":"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN) - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:40:42+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/ensayo-fase-iii-randomizado-doble-ciego-y-controlado-con-placebo-de-durvalumab-y-quimioterapia-flot-neoadyuvante-adyuvante-seguido-de-durvalumab-adyuvante-en-pacientes-con-cancer-gastrico-y-de-la-un\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Ensayo Fase III, Randomizado, Doble ciego y controlado con Placebo de Durvalumab y Quimioterapia FLOT Neoadyuvante-Adyuvante seguido de Durvalumab Adyuvante en pacientes con c\u00e1ncer g\u00e1strico y de la uni\u00f3n gastroesof\u00e1gica resecable (GC\/GEJC) (MATTERHORN)"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/32298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=32298"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/32298\/revisions"}],"predecessor-version":[{"id":55314,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/32298\/revisions\/55314"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=32298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=32298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=32298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}