{"id":32400,"date":"2025-07-30T08:41:54","date_gmt":"2025-07-30T08:41:54","guid":{"rendered":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/"},"modified":"2025-07-30T08:41:54","modified_gmt":"2025-07-30T08:41:54","slug":"estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/","title":{"rendered":"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior."},"content":{"rendered":"<p>MIGUEL ANGEL ARR\u00c1EZ S\u00c1NCHEZ &#8211; INV. CLINICA PRODUCTO SANITARIO INDEP. &#8211; No aplica &#8211; FUNDACI\u00d3N PARA LA INVESTIGACI\u00d3N BIOM\u00c9DICA DEL HOSPITAL RAM\u00d3N Y CAJAL<\/p>","protected":false},"excerpt":{"rendered":"<p>MIGUEL ANGEL ARR\u00c1EZ S\u00c1NCHEZ &#8211; INV. CLINICA PRODUCTO SANITARIO INDEP. &#8211; No aplica &#8211; FUNDACI\u00d3N PARA LA INVESTIGACI\u00d3N BIOM\u00c9DICA DEL HOSPITAL RAM\u00d3N Y CAJAL<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2283],"tags":[],"class_list":["post-32400","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-c-01-ensayos-clinicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior. - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior. - Ibima\" \/>\n<meta property=\"og:description\" content=\"MIGUEL ANGEL ARR\u00c1EZ S\u00c1NCHEZ &#8211; INV. CLINICA PRODUCTO SANITARIO INDEP. &#8211; No aplica &#8211; FUNDACI\u00d3N PARA LA INVESTIGACI\u00d3N BIOM\u00c9DICA DEL HOSPITAL RAM\u00d3N Y CAJAL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:41:54+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior.\",\"datePublished\":\"2025-07-30T08:41:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/\"},\"wordCount\":85,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - C-01\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/\",\"name\":\"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior. - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:41:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior. - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/","og_locale":"en_GB","og_type":"article","og_title":"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior. - Ibima","og_description":"MIGUEL ANGEL ARR\u00c1EZ S\u00c1NCHEZ &#8211; INV. CLINICA PRODUCTO SANITARIO INDEP. &#8211; No aplica &#8211; FUNDACI\u00d3N PARA LA INVESTIGACI\u00d3N BIOM\u00c9DICA DEL HOSPITAL RAM\u00d3N Y CAJAL","og_url":"https:\/\/ibima.eu\/en\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:41:54+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior.","datePublished":"2025-07-30T08:41:54+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/"},"wordCount":85,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - C-01"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/","url":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/","name":"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior. - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:41:54+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-controlado-aleatorizado-y-multicentrico-para-evaluar-la-seguridad-y-eficacia-de-hemopatch-en-comparacion-con-la-practica-habitual-para-el-sellado-de-duramadre-como-refuerzo-de-la-sutura-dural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio controlado aleatorizado y multic\u00e9ntrico para evaluar la seguridad y eficacia de HEMOPATCH en comparaci\u00f3n con la pr\u00e1ctica habitual para el sellado de duramadre como refuerzo de la sutura dural para la prevenci\u00f3n de fugas de l\u00edquido cefalorraqu\u00eddeo (LCR) postoperatorias en pacientes sometidos a cirug\u00eda de fosa posterior."}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/32400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=32400"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/32400\/revisions"}],"predecessor-version":[{"id":55432,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/32400\/revisions\/55432"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=32400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=32400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=32400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}