{"id":42034,"date":"2025-07-30T08:46:21","date_gmt":"2025-07-30T08:46:21","guid":{"rendered":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/"},"modified":"2025-07-30T08:46:21","modified_gmt":"2025-07-30T08:46:21","slug":"estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/","title":{"rendered":"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a"},"content":{"rendered":"<p>RAQUEL CAMARGO CAMERO &#8211; ESTUDIO NO POSAUTORIZACION &#8211; No aplica &#8211; GRUPO ESPA\u00d1OL DE TRABAJO DE ENFERMEDAD DE CROHN Y COLITIS ULCEROSA<\/p>","protected":false},"excerpt":{"rendered":"<p>RAQUEL CAMARGO CAMERO &#8211; ESTUDIO NO POSAUTORIZACION &#8211; No aplica &#8211; GRUPO ESPA\u00d1OL DE TRABAJO DE ENFERMEDAD DE CROHN Y COLITIS ULCEROSA<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2300],"tags":[],"class_list":["post-42034","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-d-05-ensayos-clinicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a - Ibima\" \/>\n<meta property=\"og:description\" content=\"RAQUEL CAMARGO CAMERO &#8211; ESTUDIO NO POSAUTORIZACION &#8211; No aplica &#8211; GRUPO ESPA\u00d1OL DE TRABAJO DE ENFERMEDAD DE CROHN Y COLITIS ULCEROSA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:46:21+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a\",\"datePublished\":\"2025-07-30T08:46:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/\"},\"wordCount\":40,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - D-05\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/\",\"name\":\"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:46:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/","og_locale":"en_GB","og_type":"article","og_title":"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a - Ibima","og_description":"RAQUEL CAMARGO CAMERO &#8211; ESTUDIO NO POSAUTORIZACION &#8211; No aplica &#8211; GRUPO ESPA\u00d1OL DE TRABAJO DE ENFERMEDAD DE CROHN Y COLITIS ULCEROSA","og_url":"https:\/\/ibima.eu\/en\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:46:21+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a","datePublished":"2025-07-30T08:46:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/"},"wordCount":40,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - D-05"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/","url":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/","name":"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:46:21+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-epidemiologico-de-la-incidencia-de-enfermedad-inflamatoria-intestinal-en-poblacion-adulta-en-espana-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio Epidemiol\u00f3gico de la incidencia de enfermedad inflamatoria intestinal en poblaci\u00f3n adulta en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/42034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=42034"}],"version-history":[{"count":2,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/42034\/revisions"}],"predecessor-version":[{"id":55863,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/42034\/revisions\/55863"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=42034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=42034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=42034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}