{"id":42569,"date":"2022-01-01T00:00:00","date_gmt":"2022-01-01T00:00:00","guid":{"rendered":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/"},"modified":"2025-07-31T07:04:34","modified_gmt":"2025-07-31T07:04:34","slug":"competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/","title":{"rendered":"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud |"},"content":{"rendered":"<p>JAIME MARTIN MARTIN &#8211;  &#8211; REGIONAL &#8211; Universidad de M\u00e1laga &#8211; 2022<\/p>","protected":false},"excerpt":{"rendered":"<p>JAIME MARTIN MARTIN &#8211; &#8211; REGIONAL &#8211; Universidad de M\u00e1laga &#8211; 2022<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2309,1528],"tags":[],"class_list":["post-42569","post","type-post","status-publish","format-standard","hentry","category-proyectos","category-proyectos-f-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud | - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud | - Ibima\" \/>\n<meta property=\"og:description\" content=\"JAIME MARTIN MARTIN &#8211; &#8211; REGIONAL &#8211; Universidad de M\u00e1laga &#8211; 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T07:04:34+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud |\",\"datePublished\":\"2022-01-01T00:00:00+00:00\",\"dateModified\":\"2025-07-31T07:04:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/\"},\"wordCount\":29,\"commentCount\":0,\"articleSection\":[\"Proyectos\",\"Proyectos - F-14\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/\",\"name\":\"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud | - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2022-01-01T00:00:00+00:00\",\"dateModified\":\"2025-07-31T07:04:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud |\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud | - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/","og_locale":"en_GB","og_type":"article","og_title":"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud | - Ibima","og_description":"JAIME MARTIN MARTIN &#8211; &#8211; REGIONAL &#8211; Universidad de M\u00e1laga &#8211; 2022","og_url":"https:\/\/ibima.eu\/en\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/","og_site_name":"Ibima","article_published_time":"2022-01-01T00:00:00+00:00","article_modified_time":"2025-07-31T07:04:34+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud |","datePublished":"2022-01-01T00:00:00+00:00","dateModified":"2025-07-31T07:04:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/"},"wordCount":29,"commentCount":0,"articleSection":["Proyectos","Proyectos - F-14"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/","url":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/","name":"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud | - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2022-01-01T00:00:00+00:00","dateModified":"2025-07-31T07:04:34+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/competencias-y-actitudes-frente-a-los-cuidades-paliativos-en-estudiantes-y-profesionales-en-ciencias-de-la-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Competencias y actitudes frente a los cuidades paliativos en estudiantes y profesionales en Ciencias de la Salud |"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/42569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=42569"}],"version-history":[{"count":1,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/42569\/revisions"}],"predecessor-version":[{"id":42868,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/42569\/revisions\/42868"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=42569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=42569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=42569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}