{"id":51616,"date":"2024-01-01T00:00:00","date_gmt":"2024-01-01T00:00:00","guid":{"rendered":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/"},"modified":"2025-04-25T09:39:44","modified_gmt":"2025-04-25T09:39:44","slug":"clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/","title":{"rendered":"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. &#8211; Neurologia"},"content":{"rendered":"<span class=\"read-more-toggle\">Ver Autores<\/span><div class=\"read-more-content\" style=\"display: none;\"><p>Sivera Mascaro, R; Garcia Sobrino, T; Horga Hernandez, A; Pelayo Negro, A L; Alonso Jimenez, A; Antelo Pose, A; Calabria Gallego, M D; Casasnovas, C; Cemillan Fernandez, C A; Esteban Perez, J; Fenollar Cortes, M; Frasquet Carrera, M; Gallano Petit, M P; Gimenez Munoz, A; Gutierrez Gutierrez, G; Gutierrez Martinez, A; Juntas Morales, R; Ciano-Petersen, N L; Martinez Ulloa, P L; Mederer Hengstl, S; Millet Sancho, E; Navacerrada Barrero, F J; Navarrete Faubel, F E; Pardo Fernandez, J; Pascual Pascual, S I; Perez Lucas, J; Pino Minguez, J; Rabasa Perez, M; Sanchez Gonzalez, M; Sotoca, J; Rodriguez Santiago, B; Rojas Garcia, R; Turon-Sans, J; Vicent Carsi, V; Sevilla Mantecon, T<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ver AutoresSivera Mascaro, R; Garcia Sobrino, T; Horga Hernandez, A; Pelayo Negro, A L; Alonso Jimenez, A; Antelo Pose, A; Calabria Gallego, M D; Casasnovas, C; Cemillan Fernandez, C A; Esteban Perez, J; Fenollar Cortes, M; Frasquet Carrera, M; Gallano Petit, M P; Gimenez Munoz, A; Gutierrez Gutierrez, G; Gutierrez Martinez, A; Juntas Morales, R; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2413],"tags":[],"class_list":["post-51616","post","type-post","status-publish","format-standard","hentry","category-guias-de-practica-clinica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. - Neurologia - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. - Neurologia - Ibima\" \/>\n<meta property=\"og:description\" content=\"Ver AutoresSivera Mascaro, R; Garcia Sobrino, T; Horga Hernandez, A; Pelayo Negro, A L; Alonso Jimenez, A; Antelo Pose, A; Calabria Gallego, M D; Casasnovas, C; Cemillan Fernandez, C A; Esteban Perez, J; Fenollar Cortes, M; Frasquet Carrera, M; Gallano Petit, M P; Gimenez Munoz, A; Gutierrez Gutierrez, G; Gutierrez Martinez, A; Juntas Morales, R; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T09:39:44+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. &#8211; Neurologia\",\"datePublished\":\"2024-01-01T00:00:00+00:00\",\"dateModified\":\"2025-04-25T09:39:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/\"},\"wordCount\":123,\"commentCount\":0,\"articleSection\":[\"Guias de Practica Clinica\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/\",\"name\":\"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. - Neurologia - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2024-01-01T00:00:00+00:00\",\"dateModified\":\"2025-04-25T09:39:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. &#8211; Neurologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. - Neurologia - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/","og_locale":"en_GB","og_type":"article","og_title":"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. - Neurologia - Ibima","og_description":"Ver AutoresSivera Mascaro, R; Garcia Sobrino, T; Horga Hernandez, A; Pelayo Negro, A L; Alonso Jimenez, A; Antelo Pose, A; Calabria Gallego, M D; Casasnovas, C; Cemillan Fernandez, C A; Esteban Perez, J; Fenollar Cortes, M; Frasquet Carrera, M; Gallano Petit, M P; Gimenez Munoz, A; Gutierrez Gutierrez, G; Gutierrez Martinez, A; Juntas Morales, R; [&hellip;]","og_url":"https:\/\/ibima.eu\/en\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/","og_site_name":"Ibima","article_published_time":"2024-01-01T00:00:00+00:00","article_modified_time":"2025-04-25T09:39:44+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. &#8211; Neurologia","datePublished":"2024-01-01T00:00:00+00:00","dateModified":"2025-04-25T09:39:44+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/"},"wordCount":123,"commentCount":0,"articleSection":["Guias de Practica Clinica"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/","url":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/","name":"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. - Neurologia - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2024-01-01T00:00:00+00:00","dateModified":"2025-04-25T09:39:44+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/clinical-practice-guidelines-for-the-diagnosis-and-management-of-charcot-marie-tooth-disease-neurologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Clinical practice guidelines for the diagnosis and management of Charcot-Marie-Tooth disease. &#8211; Neurologia"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/51616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=51616"}],"version-history":[{"count":2,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/51616\/revisions"}],"predecessor-version":[{"id":53545,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/51616\/revisions\/53545"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=51616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=51616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=51616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}