{"id":55280,"date":"2025-07-30T08:40:21","date_gmt":"2025-07-30T08:40:21","guid":{"rendered":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/"},"modified":"2025-07-30T08:40:21","modified_gmt":"2025-07-30T08:40:21","slug":"ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/","title":{"rendered":"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI)"},"content":{"rendered":"<p>JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; BOEHRINGER INGELHEIM ESPA\u00d1A, S.A.<\/p>","protected":false},"excerpt":{"rendered":"<p>JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; BOEHRINGER INGELHEIM ESPA\u00d1A, S.A.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2893],"tags":[],"class_list":["post-55280","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-de-11"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI) - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI) - Ibima\" \/>\n<meta property=\"og:description\" content=\"JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; BOEHRINGER INGELHEIM ESPA\u00d1A, S.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:40:21+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI)\",\"datePublished\":\"2025-07-30T08:40:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/\"},\"wordCount\":49,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - DE-11\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/\",\"name\":\"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI) - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:40:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI) - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/","og_locale":"en_GB","og_type":"article","og_title":"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI) - Ibima","og_description":"JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; BOEHRINGER INGELHEIM ESPA\u00d1A, S.A.","og_url":"https:\/\/ibima.eu\/en\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:40:21+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI)","datePublished":"2025-07-30T08:40:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/"},"wordCount":49,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - DE-11"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/","url":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/","name":"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI) - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:40:21+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/ensayo-doble-ciego-aleatorizado-y-controlado-con-placebo-para-evaluar-la-eficacia-y-seguridad-del-bi-1015550-durante-al-menos-52-semanas-en-pacientes-con-fibrosis-pulmonar-idiopatica-fpi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Ensayo doble ciego, aleatorizado y controlado con placebo para evaluar la eficacia y seguridad del BI 1015550 durante al menos 52 semanas en pacientes con Fibrosis Pulmonar Idiop\u00e1tica (FPI)"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/55280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=55280"}],"version-history":[{"count":0,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/55280\/revisions"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=55280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=55280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=55280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}