{"id":56054,"date":"2025-07-30T08:48:27","date_gmt":"2025-07-30T08:48:27","guid":{"rendered":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/"},"modified":"2025-07-30T08:48:27","modified_gmt":"2025-07-30T08:48:27","slug":"estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii","status":"publish","type":"post","link":"https:\/\/ibima.eu\/en\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/","title":{"rendered":"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II"},"content":{"rendered":"<p>JOSE LUIS VELASCO GARRIDO &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ASTRAZENECA FARMACEUTICA ESPA\u00d1A S.A.<\/p>","protected":false},"excerpt":{"rendered":"<p>JOSE LUIS VELASCO GARRIDO &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ASTRAZENECA FARMACEUTICA ESPA\u00d1A S.A.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2893],"tags":[],"class_list":["post-56054","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-de-11"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/en\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II - Ibima\" \/>\n<meta property=\"og:description\" content=\"JOSE LUIS VELASCO GARRIDO &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ASTRAZENECA FARMACEUTICA ESPA\u00d1A S.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/en\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:48:27+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II\",\"datePublished\":\"2025-07-30T08:48:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/\"},\"wordCount\":49,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - DE-11\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/\",\"name\":\"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:48:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/en\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/en\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/","og_locale":"en_GB","og_type":"article","og_title":"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II - Ibima","og_description":"JOSE LUIS VELASCO GARRIDO &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ESTUDIO POSAUTORIZACION COMERCIAL &#8211; ASTRAZENECA FARMACEUTICA ESPA\u00d1A S.A.","og_url":"https:\/\/ibima.eu\/en\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:48:27+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II","datePublished":"2025-07-30T08:48:27+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/"},"wordCount":49,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - DE-11"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/","url":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/","name":"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:48:27+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-observacional-retrospectivo-para-caracterizar-y-evaluar-los-resultados-clinicos-de-los-pacientes-tratados-con-benralizumab-tras-su-autorizacion-de-comercializacion-en-espana-estudio-orbe-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio observacional retrospectivo para caracterizar y evaluar los resultados cl\u00ednicos de los pacientes tratados con benralizumab tras su autorizaci\u00f3n de comercializaci\u00f3n en Espa\u00f1a. Estudio ORBE II"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/en\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/56054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/comments?post=56054"}],"version-history":[{"count":0,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/posts\/56054\/revisions"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/media?parent=56054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/categories?post=56054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/en\/wp-json\/wp\/v2\/tags?post=56054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}