{"id":19071,"date":"2022-01-01T00:00:00","date_gmt":"2022-01-01T00:00:00","guid":{"rendered":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/"},"modified":"2025-07-31T07:13:46","modified_gmt":"2025-07-31T07:13:46","slug":"pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/","title":{"rendered":"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares"},"content":{"rendered":"<p>ALMUDENA ORTEGA GOMEZ &#8211; ERNESTO GONZ\u00c1LEZ MESA &#8211; NACIONAL &#8211; INSTITUTO DE SALUD CARLOS III &#8211; 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ALMUDENA ORTEGA GOMEZ &#8211; ERNESTO GONZ\u00c1LEZ MESA &#8211; NACIONAL &#8211; INSTITUTO DE SALUD CARLOS III &#8211; 2022<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2309,1502],"tags":[],"class_list":["post-19071","post","type-post","status-publish","format-standard","hentry","category-proyectos","category-proyectos-a-02"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares - Ibima\" \/>\n<meta property=\"og:description\" content=\"ALMUDENA ORTEGA GOMEZ &#8211; ERNESTO GONZ\u00c1LEZ MESA &#8211; NACIONAL &#8211; INSTITUTO DE SALUD CARLOS III &#8211; 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T07:13:46+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares\",\"datePublished\":\"2022-01-01T00:00:00+00:00\",\"dateModified\":\"2025-07-31T07:13:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/\"},\"wordCount\":51,\"commentCount\":0,\"articleSection\":[\"Proyectos\",\"Proyectos - A-02\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/\",\"name\":\"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2022-01-01T00:00:00+00:00\",\"dateModified\":\"2025-07-31T07:13:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/","og_locale":"es_ES","og_type":"article","og_title":"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares - Ibima","og_description":"ALMUDENA ORTEGA GOMEZ &#8211; ERNESTO GONZ\u00c1LEZ MESA &#8211; NACIONAL &#8211; INSTITUTO DE SALUD CARLOS III &#8211; 2022","og_url":"https:\/\/ibima.eu\/es\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/","og_site_name":"Ibima","article_published_time":"2022-01-01T00:00:00+00:00","article_modified_time":"2025-07-31T07:13:46+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares","datePublished":"2022-01-01T00:00:00+00:00","dateModified":"2025-07-31T07:13:46+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/"},"wordCount":51,"commentCount":0,"articleSection":["Proyectos","Proyectos - A-02"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/","url":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/","name":"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2022-01-01T00:00:00+00:00","dateModified":"2025-07-31T07:13:46+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/pi22-01813-el-papel-de-los-neutrofilos-de-leche-materna-de-madres-con-enfermedades-metabolicas-tras-una-intervencion-nutricional-impacto-en-el-desarrollo-del-nino-y-respuesta-a-infecciones-pulmonares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"PI22-01813 El papel de los neutr\u00f3filos de leche materna de madres con enfermedades metab\u00f3licas tras una intervenci\u00f3n nutricional. Impacto en el desarrollo del ni\u00f1o y respuesta a infecciones pulmonares"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/19071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=19071"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/19071\/revisions"}],"predecessor-version":[{"id":56585,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/19071\/revisions\/56585"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=19071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=19071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=19071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}