{"id":32185,"date":"2025-07-30T08:39:26","date_gmt":"2025-07-30T08:39:26","guid":{"rendered":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/"},"modified":"2025-07-30T08:39:26","modified_gmt":"2025-07-30T08:39:26","slug":"ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/","title":{"rendered":"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia"},"content":{"rendered":"<p>MARIA JOSE BERMEJO PEREZ &#8211; ENSAYO CLINICO INDEPENDIENTE &#8211; II &#8211; GRUPO ESPA\u00d1OL DE INVESTIGACI\u00d3N EN C\u00c1NCER GINEC\u00d3LOGICO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARIA JOSE BERMEJO PEREZ &#8211; ENSAYO CLINICO INDEPENDIENTE &#8211; II &#8211; GRUPO ESPA\u00d1OL DE INVESTIGACI\u00d3N EN C\u00c1NCER GINEC\u00d3LOGICO<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2295],"tags":[],"class_list":["post-32185","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-b-01-ensayos-clinicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia - Ibima\" \/>\n<meta property=\"og:description\" content=\"MARIA JOSE BERMEJO PEREZ &#8211; ENSAYO CLINICO INDEPENDIENTE &#8211; II &#8211; GRUPO ESPA\u00d1OL DE INVESTIGACI\u00d3N EN C\u00c1NCER GINEC\u00d3LOGICO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:39:26+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia\",\"datePublished\":\"2025-07-30T08:39:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/\"},\"wordCount\":52,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - B-01\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/\",\"name\":\"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:39:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/","og_locale":"es_ES","og_type":"article","og_title":"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia - Ibima","og_description":"MARIA JOSE BERMEJO PEREZ &#8211; ENSAYO CLINICO INDEPENDIENTE &#8211; II &#8211; GRUPO ESPA\u00d1OL DE INVESTIGACI\u00d3N EN C\u00c1NCER GINEC\u00d3LOGICO","og_url":"https:\/\/ibima.eu\/es\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:39:26+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia","datePublished":"2025-07-30T08:39:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/"},"wordCount":52,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - B-01"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/","url":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/","name":"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:39:26+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/ensayo-aleatorizado-fase-ii-abierto-con-el-anti-pd1-tsr-042-como-terapia-de-mantenimiento-en-pacientes-con-cancer-de-cervix-localmente-avanzado-de-alto-riesgo-despues-de-quimioradioterapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Ensayo aleatorizado, fase II, abierto, con el anti-PD1 TSR-042 como terapia de mantenimiento en pacientes con c\u00e1ncer de c\u00e9rvix localmente avanzado de alto riesgo despu\u00e9s de quimioradioterapia"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=32185"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32185\/revisions"}],"predecessor-version":[{"id":55195,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32185\/revisions\/55195"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=32185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=32185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=32185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}