{"id":32424,"date":"2025-07-30T08:42:11","date_gmt":"2025-07-30T08:42:11","guid":{"rendered":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/"},"modified":"2025-07-30T08:42:11","modified_gmt":"2025-07-30T08:42:11","slug":"estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/","title":{"rendered":"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante"},"content":{"rendered":"<p>VICTORIA EUGENIA FERN\u00c1NDEZ S\u00c1NCHEZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; RECA NEURO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VICTORIA EUGENIA FERN\u00c1NDEZ S\u00c1NCHEZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; RECA NEURO<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2283],"tags":[],"class_list":["post-32424","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-c-01-ensayos-clinicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante - Ibima\" \/>\n<meta property=\"og:description\" content=\"VICTORIA EUGENIA FERN\u00c1NDEZ S\u00c1NCHEZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; RECA NEURO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:42:11+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante\",\"datePublished\":\"2025-07-30T08:42:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/\"},\"wordCount\":50,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - C-01\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/\",\"name\":\"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:42:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante - Ibima","og_description":"VICTORIA EUGENIA FERN\u00c1NDEZ S\u00c1NCHEZ &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; RECA NEURO","og_url":"https:\/\/ibima.eu\/es\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:42:11+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante","datePublished":"2025-07-30T08:42:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/"},"wordCount":50,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - C-01"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/","url":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/","name":"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:42:11+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-de-extension-del-ensayo-ac-058b301-multicentrico-no-comparativo-para-valorar-la-seguridad-tolerabilidad-y-control-de-la-enfermedad-a-largo-plazo-de-ponesimod-20-mg-en-sujetos-con-esclerosi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio de extensi\u00f3n del ensayo AC-058B301, multic\u00e9ntrico, no comparativo, para valorar la seguridad, tolerabilidad y control de la enfermedad a largo plazo de ponesimod 20 mg en sujetos con esclerosis m\u00faltiple recidivante"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=32424"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32424\/revisions"}],"predecessor-version":[{"id":55463,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32424\/revisions\/55463"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=32424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=32424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=32424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}