{"id":32530,"date":"2025-07-30T08:43:27","date_gmt":"2025-07-30T08:43:27","guid":{"rendered":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/"},"modified":"2025-07-30T08:43:27","modified_gmt":"2025-07-30T08:43:27","slug":"estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/","title":{"rendered":"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER)"},"content":{"rendered":"<p>JAVIER GARC\u00cdA CORBACHO &#8211; ENSAYO CLINICO COMERCIAL &#8211; I &#8211; TESARO, INC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JAVIER GARC\u00cdA CORBACHO &#8211; ENSAYO CLINICO COMERCIAL &#8211; I &#8211; TESARO, INC.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2295],"tags":[],"class_list":["post-32530","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-b-01-ensayos-clinicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER) - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER) - Ibima\" \/>\n<meta property=\"og:description\" content=\"JAVIER GARC\u00cdA CORBACHO &#8211; ENSAYO CLINICO COMERCIAL &#8211; I &#8211; TESARO, INC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:43:27+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER)\",\"datePublished\":\"2025-07-30T08:43:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/\"},\"wordCount\":42,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - B-01\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/\",\"name\":\"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER) - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:43:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER) - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER) - Ibima","og_description":"JAVIER GARC\u00cdA CORBACHO &#8211; ENSAYO CLINICO COMERCIAL &#8211; I &#8211; TESARO, INC.","og_url":"https:\/\/ibima.eu\/es\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:43:27+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER)","datePublished":"2025-07-30T08:43:27+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/"},"wordCount":42,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - B-01"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/","url":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/","name":"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER) - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:43:27+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-de-fase-i-con-aumento-escalonado-de-la-dosis-y-ampliacion-de-cohortes-de-tsr-022-un-anticuerpo-monoclonal-anti-tim-3-en-pacientes-con-tumores-solidos-avanzados-amber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio de fase I, con aumento escalonado de la dosis y ampliaci\u00f3n de cohortes, de TSR-022, un anticuerpo monoclonal anti-TIM-3, en pacientes con tumores s\u00f3lidos avanzados (AMBER)"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=32530"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32530\/revisions"}],"predecessor-version":[{"id":55588,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32530\/revisions\/55588"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=32530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=32530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=32530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}