{"id":32806,"date":"2025-07-30T08:46:41","date_gmt":"2025-07-30T08:46:41","guid":{"rendered":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/"},"modified":"2025-07-30T08:46:41","modified_gmt":"2025-07-30T08:46:41","slug":"estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/","title":{"rendered":"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K)"},"content":{"rendered":"<p>MIGUEL \u00c1NGEL BERCIANO GUERRERO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB, S.A.U.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIGUEL \u00c1NGEL BERCIANO GUERRERO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB, S.A.U.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2684],"tags":[],"class_list":["post-32806","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-be-23"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K) - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K) - Ibima\" \/>\n<meta property=\"og:description\" content=\"MIGUEL \u00c1NGEL BERCIANO GUERRERO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB, S.A.U.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:46:41+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\\\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K)\",\"datePublished\":\"2025-07-30T08:46:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/\"},\"wordCount\":61,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - BE-23\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/\",\"name\":\"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\\\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K) - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:46:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\\\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K) - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K) - Ibima","og_description":"MIGUEL \u00c1NGEL BERCIANO GUERRERO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB, S.A.U.","og_url":"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:46:41+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K)","datePublished":"2025-07-30T08:46:41+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/"},"wordCount":61,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - BE-23"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/","url":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/","name":"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K) - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:46:41+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-a-doble-ciego-de-inmunoterapia-adyuvante-con-nivolumab-frente-a-placebo-despues-de-reseccion-completa-de-melanoma-en-estadio-iib-c-checkmate-76k-evaluacion-en-ensayo-c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio fase 3, aleatorizado, a doble ciego, de inmunoterapia adyuvante con nivolumab frente a placebo despu\u00e9s de resecci\u00f3n completa de melanoma en estadio IIB\/C (CheckMate 76K: Evaluaci\u00f3n en ensayo cl\u00ednico de la v\u00eda de punto de control y nivolumab 76K)"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=32806"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32806\/revisions"}],"predecessor-version":[{"id":55894,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32806\/revisions\/55894"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=32806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=32806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=32806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}