{"id":32808,"date":"2025-07-30T08:46:42","date_gmt":"2025-07-30T08:46:42","guid":{"rendered":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/"},"modified":"2025-07-30T08:46:42","modified_gmt":"2025-07-30T08:46:42","slug":"estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/","title":{"rendered":"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL)"},"content":{"rendered":"<p>EMILIO ALBA CONEJO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB INTERNATIONAL CORPORATION (BMSIC)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EMILIO ALBA CONEJO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB INTERNATIONAL CORPORATION (BMSIC)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2295],"tags":[],"class_list":["post-32808","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-b-01-ensayos-clinicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL) - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL) - Ibima\" \/>\n<meta property=\"og:description\" content=\"EMILIO ALBA CONEJO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB INTERNATIONAL CORPORATION (BMSIC)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:46:42+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL)\",\"datePublished\":\"2025-07-30T08:46:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/\"},\"wordCount\":78,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - B-01\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/\",\"name\":\"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL) - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:46:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL) - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL) - Ibima","og_description":"EMILIO ALBA CONEJO &#8211; ENSAYO CLINICO COMERCIAL &#8211; III &#8211; BRISTOL-MYERS SQUIBB INTERNATIONAL CORPORATION (BMSIC)","og_url":"https:\/\/ibima.eu\/es\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:46:42+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL)","datePublished":"2025-07-30T08:46:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/"},"wordCount":78,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - B-01"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/","url":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/","name":"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL) - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:46:42+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-fase-3-aleatorizado-multicentrico-doble-ciego-controlado-con-placebo-de-nivolumab-frente-a-placebo-en-combinacion-con-quimioterapia-neoadyuvante-y-tratamiento-hormonal-adyuvante-en-pacien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio fase 3, aleatorizado, multic\u00e9ntrico, doble ciego, controlado con placebo, de nivolumab frente a placebo en combinaci\u00f3n con quimioterapia neoadyuvante y tratamiento hormonal adyuvante en pacientes con c\u00e1ncer de mama primario de alto riesgo, receptores estrog\u00e9nicos positivos (RE+) y receptor del factor de crecimiento epid\u00e9rmico humano 2 negativo (HER2-). (CheckMate 7FL: CHECKpoint pathway and nivoluMAb clinical Trial Evaluation 7FL)"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=32808"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32808\/revisions"}],"predecessor-version":[{"id":55896,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/32808\/revisions\/55896"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=32808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=32808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=32808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}