{"id":51174,"date":"2025-03-28T08:29:40","date_gmt":"2025-03-28T08:29:40","guid":{"rendered":"https:\/\/ibima.eu\/?p=51174"},"modified":"2025-11-25T10:15:43","modified_gmt":"2025-11-25T10:15:43","slug":"un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/","title":{"rendered":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb5px|||||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<div class=\"noticia-entradilla-wrapper noticia-no-foto\">\n<div class=\"noticia-entradilla-contenido\">\n<div class=\"clearfix text-formatted field field--name-sas-noticia-entradilla field--type-text-long field--label-hidden field__item\">\n<p><em><strong>Innovadoras nanopart\u00edculas mejoran la eficiencia de la hipertermia magn\u00e9tica y permiten su seguimiento en tiempo real, optimizando el tratamiento y monitorizaci\u00f3n de tumores.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Un equipo de investigadores de la Fundaci\u00f3n Progreso y Salud, que desarrolla su trabajo en el Instituto de Investigaci\u00f3n Biom\u00e9dica de M\u00e1laga y Plataforma en Nanomedicina (IBIMA Plataforma BIONAND), ha lanzado un novedoso dise\u00f1o de nanopart\u00edculas de ZnFe y ZnFe@Fe que desaf\u00eda las teor\u00edas cl\u00e1sicas sobre el crecimiento de nanopart\u00edculas y el nanomagnetismo. Este avance supone un paso crucial en la mejora de las terapias oncol\u00f3gicas mediante hipertermia magn\u00e9tica y el seguimiento preciso del tratamiento a trav\u00e9s de im\u00e1genes por resonancia magn\u00e9tica (MRI). Los hallazgos han sido publicados en la revista cient\u00edfica <em>Advanced Healthcare Materials<\/em>, consolidando el papel de IBIMA Plataforma BIONAND en la vanguardia de la nanomedicina aplicada al c\u00e1ncer.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, los investigadores pertenecen al grupo de IBIMA \u201cBiomedical Magnetic Resonance Laboratory (BMRL)\u201d que lidera la Dra. Mar\u00eda Luisa Garc\u00eda Mart\u00edn, adem\u00e1s de contar con participaci\u00f3n directa en el Centro de Investigaci\u00f3n Biom\u00e9dica en Red (CIBER-BBN).<\/p>\n<p style=\"text-align: justify;\"><strong>Repensando el crecimiento de nanopart\u00edculas y el nanomagnetismo<\/strong><\/p>\n<p style=\"text-align: justify;\">Las teor\u00edas tradicionales establecen que el crecimiento de nanopart\u00edculas y sus propiedades magn\u00e9ticas est\u00e1n limitados por su tama\u00f1o y composici\u00f3n. Sin embargo, los investigadores de IBIMA Plataforma BIONAND han logrado dise\u00f1ar nanopart\u00edculas con propiedades que superan estos l\u00edmites, logrando una eficiencia t\u00e9rmica optimizada para su aplicaci\u00f3n en terapia tumoral. Este descubrimiento podr\u00eda cambiar la forma en que se desarrollan los nanomateriales terap\u00e9uticos, ampliando sus aplicaciones en la medicina personalizada.<\/p>\n<p style=\"text-align: justify;\"><strong>Una herramienta avanzada para combatir el c\u00e1ncer<\/strong><\/p>\n<p style=\"text-align: justify;\">El dise\u00f1o de estas nanopart\u00edculas ha permitido mejorar significativamente su respuesta en hipertermia magn\u00e9tica, una estrategia terap\u00e9utica que utiliza el calor generado por las nanopart\u00edculas cuando son expuestas a un campo magn\u00e9tico alterno, permitiendo destruir selectivamente c\u00e9lulas tumorales sin afectar los tejidos sanos circundantes. Adem\u00e1s, gracias a su composici\u00f3n, estas nanopart\u00edculas ofrecen un mayor contraste en las im\u00e1genes por MRI, facilitando la monitorizaci\u00f3n de su llegada al tejido tumoral de una forma m\u00e1s precisa, facilitando as\u00ed la medicina de precisi\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong>\u2026 con una respuesta significativa<\/strong><\/p>\n<p style=\"text-align: justify;\">En estudios precl\u00ednicos, las nanopart\u00edculas de ZnFe y ZnFe@Fe han mostrado una capacidad excepcional para generar calor bajo la aplicaci\u00f3n de un campo magn\u00e9tico externo, logrando un retraso en el crecimiento de la masa tumoral de forma significativa. Adem\u00e1s, su excelente contraste para MRI permite un seguimiento detallado tanto de la llegada de las nanopart\u00edculas al tejido tumoral como de la evoluci\u00f3n del tratamiento, facilitando la toma de decisiones cl\u00ednicas m\u00e1s precisas.<\/p>\n<p style=\"text-align: justify;\">Estos resultados posicionan a IBIMA Plataforma BIONAND como un referente en la aplicaci\u00f3n de la nanotecnolog\u00eda al tratamiento del c\u00e1ncer, con un enfoque en terapias m\u00e1s eficientes, seguras y adaptadas a las necesidades individuales de cada paciente.<\/p>\n<p style=\"text-align: justify;\">Por su parte, los Dres. M\u00aa Luisa Garc\u00eda-Mart\u00edn y Carlos Caro Salazar, investigadores principales del estudio, destacan la importancia de estos hallazgos: \u201cNuestro objetivo era romper con las limitaciones impuestas por las teor\u00edas cl\u00e1sicas del nanomagnetismo y la s\u00edntesis de nanopart\u00edculas para desarrollar agentes teran\u00f3sticos m\u00e1s efectivos. Con este dise\u00f1o, hemos conseguido una notable mejora en las propiedades de estos materiales para terapia mediante hipertermia magn\u00e9tica, que se ha visto reflejado en un retraso significativo del crecimiento tumoral en modelos precl\u00ednicos tras administraci\u00f3n intravenosa. Esto supone un gran avance, ya que lo habitual es tener que recurrir a inyecci\u00f3n intratumoral para conseguir efectos terap\u00e9uticos. Adem\u00e1s, su capacidad para ser monitorizadas por MRI ofrece una ventaja crucial en la personalizaci\u00f3n de las terapias oncol\u00f3gicas.\u201d<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, los Dres. Caro Salazar y Garc\u00eda-Mart\u00edn, profesionales que han liderado dicha iniciativa, subrayan el impacto de este estudio en el campo de la nanomedicina: \u201cEste trabajo representa un avance significativo en la investigaci\u00f3n biom\u00e9dica y refuerza la posici\u00f3n de IBIMA Plataforma BIONAND como un centro de referencia en nanotecnolog\u00eda aplicada a la salud. La posibilidad de desarrollar nanopart\u00edculas con propiedades avanzadas para diagn\u00f3stico y tratamiento es un ejemplo de c\u00f3mo la ciencia puede transformar la pr\u00e1ctica cl\u00ednica y ofrecer nuevas oportunidades terap\u00e9uticas a los pacientes oncol\u00f3gicos.\u201d<\/p>\n<p style=\"text-align: justify;\"><strong>Sobre IBIMA Plataforma BIONAND<\/strong><\/p>\n<p style=\"text-align: justify;\">IBIMA Plataforma BIONAND es un instituto de investigaci\u00f3n biom\u00e9dica de referencia en Andaluc\u00eda que re\u00fane a profesionales del \u00e1mbito sanitario, acad\u00e9mico y tecnol\u00f3gico con el prop\u00f3sito de desarrollar soluciones innovadoras para mejorar la salud de la poblaci\u00f3n. Sus l\u00edneas de investigaci\u00f3n incluyen oncolog\u00eda, enfermedades metab\u00f3licas y nanomedicina, promoviendo la transferencia del conocimiento y la colaboraci\u00f3n con el sector cl\u00ednico e industrial.<\/p>\n<p style=\"text-align: justify;\"><strong>Bibliograf\u00eda<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Caro Salazar, C., Guzzi, C., Moral-S\u00e1nchez, I., Urbano-G\u00e1mez, J. D., Beltr\u00e1n, A. M., &amp; Garc\u00eda-Mart\u00edn, M. L. (2024). <\/strong><strong>Smart Design of ZnFe and ZnFe@ Fe Nanoparticles for MRI-Tracked Magnetic Hyperthermia Therapy: Challenging Classical Theories of Nanoparticles Growth and Nanomagnetism.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/doi.org\/10.1002\/adhm.202304044\"><strong>https:\/\/doi.org\/10.1002\/adhm.202304044<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<\/div>\n<\/div>\n<\/div>[\/et_pb_text][et_pb_code admin_label=\u00bbC\u00f3digo\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb4px|||||\u00bb custom_padding=\u00bb||3px|||\u00bb custom_css_free_form=\u00bbselector blockquote{||  text-align:center !important;||}\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<!--<blockquote class=\"twitter-tweet\"><pee lang=\"es\" dir=\"ltr\">\ud83d\ude80 Callsoft Inform\u00e1tica y su Expansi\u00f3n de Servicios TI<!\u2013- [et_pb_br_holder] -\u2013><!\u2013- [et_pb_br_holder] -\u2013>\u00a1Estamos emocionados! \ud83c\udf1f<!\u2013- [et_pb_br_holder] -\u2013><!\u2013- [et_pb_br_holder] -\u2013>Callsoft Inform\u00e1tica lleva su colaboraci\u00f3n con IBIMA a otro nivel. Desarrollando la nueva web de IBIMA. Agradecemos la confianza depositada.<a href=\"https:\/\/t.co\/s8WeKaLsLn\">https:\/\/t.co\/s8WeKaLsLn<\/a><a href=\"https:\/\/twitter.com\/hashtag\/IBIMA?src=hash&ref_src=twsrc%5Etfw\">#IBIMA<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ServiciosTI?src=hash&ref_src=twsrc%5Etfw\">#ServiciosTI<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Callsoft?src=hash&ref_src=twsrc%5Etfw\">#Callsoft<\/a> <a href=\"https:\/\/t.co\/5Ba0g9hq8p\">pic.twitter.com\/5Ba0g9hq8p<\/a><\/pee>\u2014 CALLSOFT INFORMATICA (@callsoft) <a href=\"https:\/\/twitter.com\/callsoft\/status\/1744685962754416820?ref_src=twsrc%5Etfw\">January 9, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>-->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Innovadoras nanopart\u00edculas mejoran la eficiencia de la hipertermia magn\u00e9tica y permiten su seguimiento en tiempo real, optimizando el tratamiento y monitorizaci\u00f3n de tumores. Un equipo de investigadores de la Fundaci\u00f3n Progreso y Salud, que desarrolla su trabajo en el Instituto de Investigaci\u00f3n Biom\u00e9dica de M\u00e1laga y Plataforma en Nanomedicina (IBIMA Plataforma BIONAND), ha lanzado un [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":51170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"noticias","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><em>IBIMA Plataforma BIONAND y Plataforma en Nanomedicina se sit\u00faa como uno de los l\u00edderes en el \u00e1mbito nacional en Investigaci\u00f3n Biom\u00e9dica<\/em><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El Instituto de Investigaci\u00f3n Biom\u00e9dica de M\u00e1laga y Plataforma en Nanomedicina (IBIMA Plataforma BIONAND) se consolida como uno de los l\u00edderes en el \u00e1mbito nacional en investigaci\u00f3n en salud. M\u00e1laga, por tanto, encabeza las investigaciones biom\u00e9dicas en Espa\u00f1a con el fin de resolver problemas de salud y en el que trabajan 1500 investigadores con dilatada experiencia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Al cierre de 2023, IBIMA Plataforma BIONAND ha obtenido una suma total de <strong>30 millones de euros<\/strong> en fondos captados para la investigaci\u00f3n en salud debido a las actividades estrat\u00e9gicas llevadas a cabo durante el a\u00f1o natural. Esto se traduce en un aumento de 6 millones de euros m\u00e1s respecto al a\u00f1o 2022.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Destaca la concesi\u00f3n de <strong>2,5 millones de euros<\/strong> del Programa FORTALECE. Este proyecto incrementar\u00e1 la actividad de I+D+i y facilitar\u00e1 la transferencia de los resultados logrados a la sociedad en forma de avances en el conocimiento, prevenci\u00f3n, diagn\u00f3stico y tratamiento de las enfermedades en patolog\u00edas relevantes (enfermedades cr\u00f3nicas, cardiovasculares, neurol\u00f3gicas y c\u00e1ncer). Adem\u00e1s, permitir\u00e1 el desarrollo de ciencia de frontera liderada por los seis grupos que lo integran: dos grupos del Hospital Universitario Virgen de la Victoria cuyos investigadores responsables son Francisco J. Tinahones y Ra\u00fal J. Andrade, dos grupos del Hospital Regional Universitario de M\u00e1laga encabezados por Mar\u00eda Jos\u00e9 Torres y por Antonia Mar\u00eda Serrano, y dos grupos de la Universidad de M\u00e1laga liderados por Jos\u00e9 Manuel Jim\u00e9nez y por Melissa Garc\u00eda.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>IBIMA Plataforma BIONAND tambi\u00e9n ha obtenido <strong>900.000 euros <\/strong>por la concesi\u00f3n de las tres plataformas del Instituto de Salud Carlos III (Innovaci\u00f3n, Ensayos Cl\u00ednicos y Biobanco), as\u00ed como el programa CERTERA con un total de <strong>400.000 euros<\/strong>, y los ensayos cl\u00ednicos independientes con <strong>valor de 800.000 euros<\/strong>. Tambi\u00e9n, entre los grandes proyectos, destacan tres en colaboraci\u00f3n p\u00fablico-privada, que re\u00fanen una financiaci\u00f3n conjunta de 3 millones de euros.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Cabe destacar el posicionamiento de <a href=\"https:\/\/ibima.eu\/investigadores-de-ibima-plataforma-bionand-demuestran-los-efectos-del-dimetil-fumarato-en-el-metabolismo-energetico\/\">IBIMA Plataforma BIONAND <\/a>en el \u00e1mbito internacional, situ\u00e1ndose a la vanguardia de la investigaci\u00f3n biom\u00e9dica de excelencia en Europa. En 2023, este reconocimiento queda avalado con la concesi\u00f3n de uno de los apoyos de mayor reconocimiento cient\u00edfico internacional, ERC Starting. Con un presupuesto de m\u00e1s de 1,4 millones de euros, este Instituto se enfrenta a un gran desaf\u00edo cient\u00edfico en la prevenci\u00f3n y predicci\u00f3n del infarto de miocardio, que supondr\u00e1 un gran avance en la frontera del conocimiento, generando un importante impacto cient\u00edfico con traslaci\u00f3n cl\u00ednica. Adicionalmente, cabe resaltar\u00a0 la atracci\u00f3n de talento internacional con la concesi\u00f3n del Marie Slowdoska Curie en el \u00e1rea de alergia, tres proyectos financiados en el marco del programa EU4Health y otros tres dentro del cl\u00faster salud de Horizonte Europa en colaboraci\u00f3n con la European Clinical Research Infrastructure Network (ECRIN)<a href=\"https:\/\/ecrin.org\/\">.<\/a> IBIMA Plataforma BIONAND cierra este 2023 con tres nuevos proyectos en resoluci\u00f3n provisional de las convocatorias SUDOE, ERA4Health y EU4Health, que generar\u00e1 nuevas colaboraciones y resultados con impacto internacional.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En este a\u00f1o que finaliza ha sido muy significativo el incremento de ensayos cl\u00ednicos desarrollados en el Instituto. Actualmente el centro participa en 325 ensayos cl\u00ednicos, lo que supone un incremento del <strong>24% respecto al a\u00f1o 2022<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Asimismo, parte del \u00e9xito de IBIMA Plataforma BIONAND reside en la aportaci\u00f3n activa de la participaci\u00f3n ciudadana. Eventos como el I Torneo de F\u00fatbol 7 HRUM\/IBIMA o la I Carrera Solidaria Contra la Obesidad han sido parte de las acciones llevadas a cabo y donde se han recaudado alrededor de 30.000 euros para fomentar la investigaci\u00f3n biom\u00e9dica.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Especial importancia para el crecimiento del Instituto ha tenido el acto solidario de Francisco Jes\u00fas Sarmiento, que ha donado, en concepto de herencia, un total de <strong>230.000 euros<\/strong> para el desarrollo de distintas l\u00edneas de investigaci\u00f3n en el Instituto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u201cM\u00e1laga cuenta con un centro de excelencia en Investigaci\u00f3n Biom\u00e9dica. Es IBIMA Plataforma BIONAND, que, en estos \u00faltimos a\u00f1os, ha tenido un crecimiento sostenido en la captaci\u00f3n de recursos, acerc\u00e1ndonos este a\u00f1o a los<strong> 30 millones de euros<\/strong>. Esto supone que IBIMA Plataforma BIONAND se posicione como uno de los Institutos de Investigaci\u00f3n Biom\u00e9dica m\u00e1s relevante de nuestro pa\u00eds\u201d, ha se\u00f1alado Francisco J. Tinahones, director cient\u00edfico del Instituto de Investigaci\u00f3n Biom\u00e9dica de M\u00e1laga y Plataforma en Nanomedicina.<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[1981],"tags":[2104,1983,2230,2742,2740,2743,2103,2187],"class_list":["post-51174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-diagnostico","tag-ibima-plataforma-bionand","tag-investigacion","tag-investigacion-oncologica","tag-nanomagnetismo","tag-nanoparticulas","tag-oncologia","tag-tratamiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen - Ibima<\/title>\n<meta name=\"description\" content=\"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen desde M\u00e1laga\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen - Ibima\" \/>\n<meta property=\"og:description\" content=\"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen desde M\u00e1laga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-28T08:29:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T10:15:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibima.eu\/wp-content\/uploads\/2025\/03\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Divulgaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Divulgaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/\"},\"author\":{\"name\":\"Divulgaci\u00f3n\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/31b8becdcc53729d5a51d5b3436ce9a5\"},\"headline\":\"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen\",\"datePublished\":\"2025-03-28T08:29:40+00:00\",\"dateModified\":\"2025-11-25T10:15:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/\"},\"wordCount\":1056,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibima.eu\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg\",\"keywords\":[\"diagn\u00f3stico\",\"IBIMA Plataforma BIONAND\",\"Investigacion\",\"investigaci\u00f3n oncol\u00f3gica\",\"Nanomagnetismo\",\"nanopart\u00edculas\",\"oncolog\u00eda\",\"tratamiento\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/\",\"name\":\"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibima.eu\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg\",\"datePublished\":\"2025-03-28T08:29:40+00:00\",\"dateModified\":\"2025-11-25T10:15:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/31b8becdcc53729d5a51d5b3436ce9a5\"},\"description\":\"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen desde M\u00e1laga\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibima.eu\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg\",\"contentUrl\":\"https:\\\/\\\/ibima.eu\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"NP CCaro Nanopart\u00edculas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/31b8becdcc53729d5a51d5b3436ce9a5\",\"name\":\"Divulgaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a96ea83ae1abdc712e138b425847bdc88b61da083b2e05603d5a5305a98cd781?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a96ea83ae1abdc712e138b425847bdc88b61da083b2e05603d5a5305a98cd781?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a96ea83ae1abdc712e138b425847bdc88b61da083b2e05603d5a5305a98cd781?s=96&d=mm&r=g\",\"caption\":\"Divulgaci\u00f3n\"},\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/divulgacioncientifica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen - Ibima","description":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen desde M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/","og_locale":"es_ES","og_type":"article","og_title":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen - Ibima","og_description":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen desde M\u00e1laga","og_url":"https:\/\/ibima.eu\/es\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/","og_site_name":"Ibima","article_published_time":"2025-03-28T08:29:40+00:00","article_modified_time":"2025-11-25T10:15:43+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/ibima.eu\/wp-content\/uploads\/2025\/03\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg","type":"image\/jpeg"}],"author":"Divulgaci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Divulgaci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/"},"author":{"name":"Divulgaci\u00f3n","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/31b8becdcc53729d5a51d5b3436ce9a5"},"headline":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen","datePublished":"2025-03-28T08:29:40+00:00","dateModified":"2025-11-25T10:15:43+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/"},"wordCount":1056,"commentCount":0,"image":{"@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#primaryimage"},"thumbnailUrl":"https:\/\/ibima.eu\/wp-content\/uploads\/2025\/03\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg","keywords":["diagn\u00f3stico","IBIMA Plataforma BIONAND","Investigacion","investigaci\u00f3n oncol\u00f3gica","Nanomagnetismo","nanopart\u00edculas","oncolog\u00eda","tratamiento"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/","url":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/","name":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#primaryimage"},"image":{"@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#primaryimage"},"thumbnailUrl":"https:\/\/ibima.eu\/wp-content\/uploads\/2025\/03\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg","datePublished":"2025-03-28T08:29:40+00:00","dateModified":"2025-11-25T10:15:43+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/31b8becdcc53729d5a51d5b3436ce9a5"},"description":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen desde M\u00e1laga","breadcrumb":{"@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#primaryimage","url":"https:\/\/ibima.eu\/wp-content\/uploads\/2025\/03\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg","contentUrl":"https:\/\/ibima.eu\/wp-content\/uploads\/2025\/03\/Post-de-Instagram-Vertical-Frase-Inspiradora-Minimalista-y-Sencillo-Gris-y-Negro.jpg","width":1080,"height":1350,"caption":"NP CCaro Nanopart\u00edculas"},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/un-nuevo-diseno-de-nanoparticulas-optimiza-las-terapias-contra-el-cancer-y-mejora-el-seguimiento-por-imagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Un nuevo dise\u00f1o de nanopart\u00edculas optimiza las terapias contra el c\u00e1ncer y mejora el seguimiento por imagen"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/31b8becdcc53729d5a51d5b3436ce9a5","name":"Divulgaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a96ea83ae1abdc712e138b425847bdc88b61da083b2e05603d5a5305a98cd781?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a96ea83ae1abdc712e138b425847bdc88b61da083b2e05603d5a5305a98cd781?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a96ea83ae1abdc712e138b425847bdc88b61da083b2e05603d5a5305a98cd781?s=96&d=mm&r=g","caption":"Divulgaci\u00f3n"},"url":"https:\/\/ibima.eu\/es\/author\/divulgacioncientifica\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/51174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=51174"}],"version-history":[{"count":3,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/51174\/revisions"}],"predecessor-version":[{"id":51181,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/51174\/revisions\/51181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media\/51170"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=51174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=51174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=51174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}