{"id":51690,"date":"2024-01-01T00:00:00","date_gmt":"2024-01-01T00:00:00","guid":{"rendered":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/"},"modified":"2025-07-31T07:55:44","modified_gmt":"2025-07-31T07:55:44","slug":"development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/","title":{"rendered":"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) &#8211; JOURNAL OF TISSUE VIABILITY"},"content":{"rendered":"<p>Mart\u00ednez-Sebasti\u00e1n C, Gijon-Nogueron G, Ramos-Petersen L, Morales-Asencio JM, Molina-Garc\u00eda C, Evans AM &#8211; 2024 &#8211; 10.1016\/j.jtv.2024.05.010<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mart\u00ednez-Sebasti\u00e1n C, Gijon-Nogueron G, Ramos-Petersen L, Morales-Asencio JM, Molina-Garc\u00eda C, Evans AM &#8211; 2024 &#8211; 10.1016\/j.jtv.2024.05.010<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2837],"tags":[],"class_list":["post-51690","post","type-post","status-publish","format-standard","hentry","category-publicaciones-ce-23"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) - JOURNAL OF TISSUE VIABILITY - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) - JOURNAL OF TISSUE VIABILITY - Ibima\" \/>\n<meta property=\"og:description\" content=\"Mart\u00ednez-Sebasti\u00e1n C, Gijon-Nogueron G, Ramos-Petersen L, Morales-Asencio JM, Molina-Garc\u00eda C, Evans AM &#8211; 2024 &#8211; 10.1016\/j.jtv.2024.05.010\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T07:55:44+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) &#8211; JOURNAL OF TISSUE VIABILITY\",\"datePublished\":\"2024-01-01T00:00:00+00:00\",\"dateModified\":\"2025-07-31T07:55:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/\"},\"wordCount\":36,\"commentCount\":0,\"articleSection\":[\"Publicaciones - CE-23\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/\",\"name\":\"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) - JOURNAL OF TISSUE VIABILITY - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2024-01-01T00:00:00+00:00\",\"dateModified\":\"2025-07-31T07:55:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) &#8211; JOURNAL OF TISSUE VIABILITY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) - JOURNAL OF TISSUE VIABILITY - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/","og_locale":"es_ES","og_type":"article","og_title":"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) - JOURNAL OF TISSUE VIABILITY - Ibima","og_description":"Mart\u00ednez-Sebasti\u00e1n C, Gijon-Nogueron G, Ramos-Petersen L, Morales-Asencio JM, Molina-Garc\u00eda C, Evans AM &#8211; 2024 &#8211; 10.1016\/j.jtv.2024.05.010","og_url":"https:\/\/ibima.eu\/es\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/","og_site_name":"Ibima","article_published_time":"2024-01-01T00:00:00+00:00","article_modified_time":"2025-07-31T07:55:44+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) &#8211; JOURNAL OF TISSUE VIABILITY","datePublished":"2024-01-01T00:00:00+00:00","dateModified":"2025-07-31T07:55:44+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/"},"wordCount":36,"commentCount":0,"articleSection":["Publicaciones - CE-23"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/","url":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/","name":"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) - JOURNAL OF TISSUE VIABILITY - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2024-01-01T00:00:00+00:00","dateModified":"2025-07-31T07:55:44+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/development-validation-and-psychometric-analysis-of-foot-and-ankle-flexibility-index-fafi-journal-of-tissue-viability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Development, validation, and psychometric analysis of Foot and Ankle Flexibility Index (FAFI) &#8211; JOURNAL OF TISSUE VIABILITY"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/51690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=51690"}],"version-history":[{"count":2,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/51690\/revisions"}],"predecessor-version":[{"id":54690,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/51690\/revisions\/54690"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=51690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=51690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=51690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}