{"id":55503,"date":"2025-07-30T08:42:37","date_gmt":"2025-07-30T08:42:37","guid":{"rendered":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/"},"modified":"2025-07-30T08:42:37","modified_gmt":"2025-07-30T08:42:37","slug":"estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/","title":{"rendered":"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo"},"content":{"rendered":"<p>ALICIA PADILLA GALO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; PAREXEL INTERNATIONAL (IRL) LIMITED<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ALICIA PADILLA GALO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; PAREXEL INTERNATIONAL (IRL) LIMITED<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2893],"tags":[],"class_list":["post-55503","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-de-11"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo - Ibima\" \/>\n<meta property=\"og:description\" content=\"ALICIA PADILLA GALO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; PAREXEL INTERNATIONAL (IRL) LIMITED\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:42:37+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo\",\"datePublished\":\"2025-07-30T08:42:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/\"},\"wordCount\":66,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - DE-11\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/\",\"name\":\"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:42:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo - Ibima","og_description":"ALICIA PADILLA GALO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; PAREXEL INTERNATIONAL (IRL) LIMITED","og_url":"https:\/\/ibima.eu\/es\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:42:37+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo","datePublished":"2025-07-30T08:42:37+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/"},"wordCount":66,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - DE-11"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/","url":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/","name":"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:42:37+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-de-fase-2-aleatorizado-en-doble-ciego-y-controlado-con-placebo-para-evaluar-la-eficacia-y-la-seguridad-de-distintos-niveles-de-dosis-de-atuliflapon-en-administracion-oral-una-vez-al-dia-du\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio de fase 2, aleatorizado, en doble ciego y controlado con placebo, para evaluar la eficacia y la seguridad de distintos niveles de dosis de atuliflap\u00f3n, en administraci\u00f3n oral una vez al d\u00eda durante 12 semanas, en adultos con asma no controlada de grado moderado o severo"}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/55503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=55503"}],"version-history":[{"count":0,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/55503\/revisions"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=55503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=55503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=55503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}