{"id":55846,"date":"2025-07-30T08:46:12","date_gmt":"2025-07-30T08:46:12","guid":{"rendered":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/"},"modified":"2025-07-30T08:46:12","modified_gmt":"2025-07-30T08:46:12","slug":"estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c","status":"publish","type":"post","link":"https:\/\/ibima.eu\/es\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/","title":{"rendered":"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1)."},"content":{"rendered":"<p>JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; IQVIA LTD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; IQVIA LTD.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2263,2893],"tags":[],"class_list":["post-55846","post","type-post","status-publish","format-standard","hentry","category-ensayos-clinicos","category-ensayos-clinicos-de-11"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1). - Ibima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibima.eu\/es\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1). - Ibima\" \/>\n<meta property=\"og:description\" content=\"JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; IQVIA LTD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibima.eu\/es\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibima\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T08:46:12+00:00\" \/>\n<meta name=\"author\" content=\"prodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prodriguez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/\"},\"author\":{\"name\":\"prodriguez\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"headline\":\"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1).\",\"datePublished\":\"2025-07-30T08:46:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/\"},\"wordCount\":57,\"commentCount\":0,\"articleSection\":[\"Ensayos Cl\u00ednicos\",\"Ensayos Cl\u00ednicos - DE-11\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/\",\"url\":\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/\",\"name\":\"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1). - Ibima\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-07-30T08:46:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/\",\"name\":\"Ibima\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibima.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibima.eu\\\/es\\\/#\\\/schema\\\/person\\\/40b410344dd5ad2315bb651e3fbfa635\",\"name\":\"prodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g\",\"caption\":\"prodriguez\"},\"sameAs\":[\"https:\\\/\\\/ibima.eu\"],\"url\":\"https:\\\/\\\/ibima.eu\\\/es\\\/author\\\/prodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1). - Ibima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibima.eu\/es\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1). - Ibima","og_description":"JOSE LUIS VELASCO GARRIDO &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; ENSAYO CLINICO CON MEDICAMENTOS &#8211; IQVIA LTD.","og_url":"https:\/\/ibima.eu\/es\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/","og_site_name":"Ibima","article_published_time":"2025-07-30T08:46:12+00:00","author":"prodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prodriguez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/#article","isPartOf":{"@id":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/"},"author":{"name":"prodriguez","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"headline":"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1).","datePublished":"2025-07-30T08:46:12+00:00","mainEntityOfPage":{"@id":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/"},"wordCount":57,"commentCount":0,"articleSection":["Ensayos Cl\u00ednicos","Ensayos Cl\u00ednicos - DE-11"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/","url":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/","name":"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1). - Ibima","isPartOf":{"@id":"https:\/\/ibima.eu\/es\/#website"},"datePublished":"2025-07-30T08:46:12+00:00","author":{"@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635"},"breadcrumb":{"@id":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibima.eu\/estudio-en-fase-iii-de-52-semanas-aleatorizado-doble-ciego-controlado-con-placebo-de-grupos-paralelos-con-unaextension-abierta-sobre-la-eficacia-y-seguridad-de-blu-5937-en-participantes-adultos-c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibima.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estudio en fase III, de 52 semanas, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos con unaextensi\u00f3n abierta sobre la eficacia y seguridad de BLU-5937 en participantes adultos con tos cr\u00f3nica refractaria, incluida tos cr\u00f3nica inexplicada (CALM-1)."}]},{"@type":"WebSite","@id":"https:\/\/ibima.eu\/es\/#website","url":"https:\/\/ibima.eu\/es\/","name":"Ibima","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibima.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ibima.eu\/es\/#\/schema\/person\/40b410344dd5ad2315bb651e3fbfa635","name":"prodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e682b55f425f54644efd95284b890bfd6e129cc61dd791a9d4345ce1ed26791?s=96&d=mm&r=g","caption":"prodriguez"},"sameAs":["https:\/\/ibima.eu"],"url":"https:\/\/ibima.eu\/es\/author\/prodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/55846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/comments?post=55846"}],"version-history":[{"count":0,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/posts\/55846\/revisions"}],"wp:attachment":[{"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/media?parent=55846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/categories?post=55846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibima.eu\/es\/wp-json\/wp\/v2\/tags?post=55846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}